{"id":25296,"date":"2025-07-31T12:01:24","date_gmt":"2025-07-31T10:01:24","guid":{"rendered":"https:\/\/imredd.fr\/?post_type=projet&#038;p=25296"},"modified":"2026-02-16T11:38:49","modified_gmt":"2026-02-16T10:38:49","slug":"green-mov","status":"publish","type":"projet","link":"https:\/\/imredd.fr\/en\/projet\/greenmov\/","title":{"rendered":"GreenMov"},"excerpt":{"rendered":"<p>Open data and sustainable mobility for intelligent ecosystems<\/p>","protected":false},"featured_media":25297,"parent":0,"menu_order":0,"template":"","statut_projet":[449],"type_projet":[464],"class_list":["post-25296","projet","type-projet","status-publish","has-post-thumbnail","hentry","statut_projet-projet-acheve","type_projet-projet-collaboratif","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>GreenMov - IMREDD - Universit\u00e9 C\u00f4te d&#039;Azur<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/imredd.fr\/en\/project\/green-mov\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GreenMov\" \/>\n<meta property=\"og:description\" content=\"Donn\u00e9es ouvertes et mobilit\u00e9 durable pour des \u00e9cosyst\u00e8mes intelligents\" \/>\n<meta property=\"og:url\" content=\"https:\/\/imredd.fr\/en\/project\/green-mov\/\" \/>\n<meta property=\"og:site_name\" content=\"IMREDD - Universit\u00e9 C\u00f4te d&#039;Azur\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/imredd.uca\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-16T10:38:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/imredd.fr\\\/projet\\\/greenmov\\\/\",\"url\":\"https:\\\/\\\/imredd.fr\\\/projet\\\/greenmov\\\/\",\"name\":\"GreenMov - IMREDD - Universit\u00e9 C\u00f4te d&#039;Azur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/imredd.fr\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/imredd.fr\\\/projet\\\/greenmov\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/imredd.fr\\\/projet\\\/greenmov\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/imredd.fr\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/featur-greenmove.webp\",\"datePublished\":\"2025-07-31T10:01:24+00:00\",\"dateModified\":\"2026-02-16T10:38:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/imredd.fr\\\/projet\\\/greenmov\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/imredd.fr\\\/projet\\\/greenmov\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/imredd.fr\\\/projet\\\/greenmov\\\/#primaryimage\",\"url\":\"https:\\\/\\\/imredd.fr\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/featur-greenmove.webp\",\"contentUrl\":\"https:\\\/\\\/imredd.fr\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/featur-greenmove.webp\",\"width\":1440,\"height\":1081},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/imredd.fr\\\/projet\\\/greenmov\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/imredd.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects and Chairs\",\"item\":\"https:\\\/\\\/imredd.fr\\\/en\\\/project\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"GreenMov\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/imredd.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/imredd.fr\\\/en\\\/\",\"name\":\"IMREDD - Universit\u00e9 C\u00f4te d'Azur\",\"description\":\"Institut M\u00e9diterran\u00e9en du Risque, de l&#039;Environnement et du D\u00e9veloppement Durable\",\"publisher\":{\"@id\":\"https:\\\/\\\/imredd.fr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/imredd.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/imredd.fr\\\/en\\\/#organization\",\"name\":\"IMREDD - Institut M\u00e9diterran\u00e9en du Risque, de l'Environnement et du D\u00e9veloppement Durable\",\"url\":\"https:\\\/\\\/imredd.fr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/imredd.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/imredd.fr\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/IMREDD-Logo-couleurs-transparent.png\",\"contentUrl\":\"https:\\\/\\\/imredd.fr\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/IMREDD-Logo-couleurs-transparent.png\",\"width\":959,\"height\":164,\"caption\":\"IMREDD - Institut M\u00e9diterran\u00e9en du Risque, de l'Environnement et du D\u00e9veloppement Durable\"},\"image\":{\"@id\":\"https:\\\/\\\/imredd.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/imredd.uca\",\"http:\\\/\\\/linkedin.com\\\/showcase\\\/imredd\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"GreenMov - IMREDD - Universit\u00e9 C\u00f4te d'Azur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/imredd.fr\/en\/project\/green-mov\/","og_locale":"en_GB","og_type":"article","og_title":"GreenMov","og_description":"Donn\u00e9es ouvertes et mobilit\u00e9 durable pour des \u00e9cosyst\u00e8mes intelligents","og_url":"https:\/\/imredd.fr\/en\/project\/green-mov\/","og_site_name":"IMREDD - Universit\u00e9 C\u00f4te d&#039;Azur","article_publisher":"http:\/\/facebook.com\/imredd.uca","article_modified_time":"2026-02-16T10:38:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/imredd.fr\/projet\/greenmov\/","url":"https:\/\/imredd.fr\/projet\/greenmov\/","name":"GreenMov - IMREDD - Universit\u00e9 C\u00f4te d'Azur","isPartOf":{"@id":"https:\/\/imredd.fr\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/imredd.fr\/projet\/greenmov\/#primaryimage"},"image":{"@id":"https:\/\/imredd.fr\/projet\/greenmov\/#primaryimage"},"thumbnailUrl":"https:\/\/imredd.fr\/wp-content\/uploads\/2025\/07\/featur-greenmove.webp","datePublished":"2025-07-31T10:01:24+00:00","dateModified":"2026-02-16T10:38:49+00:00","breadcrumb":{"@id":"https:\/\/imredd.fr\/projet\/greenmov\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/imredd.fr\/projet\/greenmov\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/imredd.fr\/projet\/greenmov\/#primaryimage","url":"https:\/\/imredd.fr\/wp-content\/uploads\/2025\/07\/featur-greenmove.webp","contentUrl":"https:\/\/imredd.fr\/wp-content\/uploads\/2025\/07\/featur-greenmove.webp","width":1440,"height":1081},{"@type":"BreadcrumbList","@id":"https:\/\/imredd.fr\/projet\/greenmov\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/imredd.fr\/"},{"@type":"ListItem","position":2,"name":"Projects and Chairs","item":"https:\/\/imredd.fr\/en\/project\/"},{"@type":"ListItem","position":3,"name":"GreenMov"}]},{"@type":"WebSite","@id":"https:\/\/imredd.fr\/en\/#website","url":"https:\/\/imredd.fr\/en\/","name":"IMREDD - C\u00f4te d'Azur University","description":"Mediterranean Institute for Risk, Environment and Sustainable Development","publisher":{"@id":"https:\/\/imredd.fr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/imredd.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/imredd.fr\/en\/#organization","name":"IMREDD - Mediterranean Institute for Risk, Environment and Sustainable Development","url":"https:\/\/imredd.fr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/imredd.fr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/imredd.fr\/wp-content\/uploads\/2025\/07\/IMREDD-Logo-couleurs-transparent.png","contentUrl":"https:\/\/imredd.fr\/wp-content\/uploads\/2025\/07\/IMREDD-Logo-couleurs-transparent.png","width":959,"height":164,"caption":"IMREDD - Institut M\u00e9diterran\u00e9en du Risque, de l'Environnement et du D\u00e9veloppement Durable"},"image":{"@id":"https:\/\/imredd.fr\/en\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/imredd.uca","http:\/\/linkedin.com\/showcase\/imredd"]}]}},"ptb_metabox":{"ptb_projet_descriptio":"L\u2019objectif du projet est d\u2019harmoniser les mod\u00e8les de donn\u00e9es et de poursuivre les services de mobilit\u00e9 verte gr\u00e2ce \u00e0 des ensembles de donn\u00e9es ouvertes de grande valeur fournis par les villes europ\u00e9ennes via plusieurs portails de donn\u00e9es ouvertes.\r\n\r\nDe nos jours, les villes collectent et publient des donn\u00e9es sur la mobilit\u00e9 sous forme de donn\u00e9es ouvertes, et les fournisseurs de technologies de l\u2019information d\u00e9veloppent des outils et des applications qui analysent et exploitent ces donn\u00e9es sous forme de services pour les citoyens, les entreprises et les administrations publiques. Malgr\u00e9 l\u2019\u00e9norme quantit\u00e9 de donn\u00e9es produites et utilis\u00e9es ces derniers temps, il existe encore des possibilit\u00e9s d\u2019am\u00e9lioration en termes d\u2019harmonisation des donn\u00e9es pour permettre des services de qualit\u00e9 int\u00e9grant des donn\u00e9es provenant de sources diff\u00e9rentes.\r\n\r\nGr\u00e2ce \u00e0 son approche technique, GreenMov permettra l\u2019interop\u00e9rabilit\u00e9 entre les villes et les r\u00e9gions pour le partage des donn\u00e9es, des services et m\u00eame des avantages li\u00e9s \u00e0 la r\u00e9duction des co\u00fbts, \u00e0 l\u2019engagement environnemental, \u00e0 la satisfaction des citoyens et \u00e0 la cr\u00e9ation de nouvelles opportunit\u00e9s commerciales bas\u00e9es sur le d\u00e9veloppement plus facile de services \u00e0 valeur ajout\u00e9e pour la mobilit\u00e9 et la facilitation de l\u2019acc\u00e8s aux donn\u00e9es ouvertes sur la mobilit\u00e9.\r\n\r\nGr\u00e2ce \u00e0 GreenMov, la mobilit\u00e9 verte et intelligente sera am\u00e9lior\u00e9e pour les citoyens, les entreprises et les administrations publiques autour de trois objectifs :\r\n<ul>\r\n \t<li>La d\u00e9finition de Mod\u00e8les de Donn\u00e9es Intelligents et d\u2019un Vocabulaire de Base pour\u00a0<strong>harmoniser les diff\u00e9rents ensembles de donn\u00e9es<\/strong>.<\/li>\r\n \t<li>Le d\u00e9veloppement de services crois\u00e9s pour connecter diverses sources de donn\u00e9es et\u00a0<strong>promouvoir des fonctionnalit\u00e9s partag\u00e9es<\/strong>.<\/li>\r\n \t<li>L\u2019efficacit\u00e9 \u00e9conomique et environnementale gr\u00e2ce \u00e0 une\u00a0<strong>meilleure coordination entre les villes et les r\u00e9gions<\/strong>\u00a0par le biais de portails de donn\u00e9es.<\/li>\r\n<\/ul>\r\nEn plus de ces trois objectifs fondamentaux, GreenMov fournira une architecture conceptuelle bas\u00e9e sur le Building Block Context Broker pour l\u2019utilisation intensive et les fonctionnalit\u00e9s en temps r\u00e9el dans n\u2019importe quel sc\u00e9nario de mobilit\u00e9, visant une architecture sans serveur pour atteindre une \u00e9volutivit\u00e9 horizontale qui sera valid\u00e9e sur trois pilotes r\u00e9els :\r\n<ul>\r\n \t<li>surveillance du bruit et de la pollution atmosph\u00e9rique pour une mobilit\u00e9 plus efficace (Nice, France) ;<\/li>\r\n \t<li>catalyseur durable pour la r\u00e9utilisation des donn\u00e9es de mobilit\u00e9 intelligente et verte (r\u00e9gion flamande, Belgique) ;<\/li>\r\n \t<li>et am\u00e9lioration des flux de mobilit\u00e9, de l\u2019intramodalit\u00e9 et des param\u00e8tres environnementaux (Murcia\/Molina de Segura, Espagne).<\/li>\r\n<\/ul>","ptb_site_projet":["Site du projet","https:\/\/green-mov.eu\/green-mobility-data-models-and-services-smart-ecosystems"],"ptb_projet_related_partner":{"relType":"1","ids":"25298, 25308, 25309, 25310, 25311, 25312, 25315, 25316, 26885"},"ptb_projet_financeur_projet":{"relType":"1","ids":"25181"},"ptb_projet_mention":"Ce projet est financ\u00e9 par l'Union europ\u00e9enne dans le cadre du dispositif Connecting Europe Facility.","ptb_projet_project_related_post":{"relType":"2","ids":"368"},"ptb_projet_publi_scientif_en_lien":{"relType":"2","ids":"497"}},"ptb_taxonomy":{"statut_projet":[{"term_id":449,"name":"Projet achev\u00e9","slug":"projet-acheve","term_group":0,"term_taxonomy_id":449,"taxonomy":"statut_projet","description":"","parent":0,"count":7,"filter":"raw"}],"type_projet":[{"term_id":464,"name":"Projet collaboratif","slug":"projet-collaboratif","term_group":0,"term_taxonomy_id":464,"taxonomy":"type_projet","description":"","parent":0,"count":17,"filter":"raw"}]},"ptb_featured_image":{"url":"https:\/\/imredd.fr\/wp-content\/uploads\/2025\/07\/featur-greenmove.webp","title":"featur-greenmove","caption":""},"_links":{"self":[{"href":"https:\/\/imredd.fr\/en\/wp-json\/wp\/v2\/projet\/25296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imredd.fr\/en\/wp-json\/wp\/v2\/projet"}],"about":[{"href":"https:\/\/imredd.fr\/en\/wp-json\/wp\/v2\/types\/projet"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imredd.fr\/en\/wp-json\/wp\/v2\/media\/25297"}],"wp:attachment":[{"href":"https:\/\/imredd.fr\/en\/wp-json\/wp\/v2\/media?parent=25296"}],"wp:term":[{"taxonomy":"statut_projet","embeddable":true,"href":"https:\/\/imredd.fr\/en\/wp-json\/wp\/v2\/statut_projet?post=25296"},{"taxonomy":"type_projet","embeddable":true,"href":"https:\/\/imredd.fr\/en\/wp-json\/wp\/v2\/type_projet?post=25296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}